{"id":122123,"date":"2021-01-19T11:15:01","date_gmt":"2021-01-19T11:15:01","guid":{"rendered":"https:\/\/euro.staging.lowe-and-fletcher.co.uk\/cames\/"},"modified":"2022-08-31T11:16:54","modified_gmt":"2022-08-31T10:16:54","slug":"cames","status":"publish","type":"page","link":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/","title":{"rendered":"Cames"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":56659,"parent":122128,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"templates\/technical-resources.php","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-122123","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Came | Came pour Serrure | Euro-Locks Belgique<\/title>\n<meta name=\"description\" content=\"Une came est la plaque ou le bras m\u00e9tallique qui, lorsque la serrure est actionn\u00e9e, ouvre ou ferme la serrure. Vous ne savez pas quelle taille de came commander ? Cette page contient des informations sur la mani\u00e8re de sp\u00e9cifier la came dont vous avez beso\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Came | Came pour Serrure | Euro-Locks Belgique\" \/>\n<meta property=\"og:description\" content=\"44\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/\" \/>\n<meta property=\"og:site_name\" content=\"Euro-Locks Belgique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T10:16:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/cames\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/cames\\\/\",\"name\":\"Came | Came pour Serrure | Euro-Locks Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/cames\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/cames\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/C807-500x400-4.png\",\"datePublished\":\"2021-01-19T11:15:01+00:00\",\"dateModified\":\"2022-08-31T10:16:54+00:00\",\"description\":\"Une came est la plaque ou le bras m\u00e9tallique qui, lorsque la serrure est actionn\u00e9e, ouvre ou ferme la serrure. Vous ne savez pas quelle taille de came commander ? Cette page contient des informations sur la mani\u00e8re de sp\u00e9cifier la came dont vous avez beso\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/cames\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/cames\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/cames\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/C807-500x400-4.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/C807-500x400-4.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/cames\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serrure Aide\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Informations techniques pour les serrures\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/aide\\\/informations-techniques\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cames\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#website\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\",\"name\":\"Euro-Locks Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#organization\",\"name\":\"Euro-Locks\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"width\":222,\"height\":58,\"caption\":\"Euro-Locks\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/euro-locks-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LoweAndFletcherGroup\",\"https:\\\/\\\/www.instagram.com\\\/lowefletchergroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Came | Came pour Serrure | Euro-Locks Belgique","description":"Une came est la plaque ou le bras m\u00e9tallique qui, lorsque la serrure est actionn\u00e9e, ouvre ou ferme la serrure. Vous ne savez pas quelle taille de came commander ? Cette page contient des informations sur la mani\u00e8re de sp\u00e9cifier la came dont vous avez beso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/","og_locale":"fr_FR","og_type":"article","og_title":"Came | Came pour Serrure | Euro-Locks Belgique","og_description":"44","og_url":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/","og_site_name":"Euro-Locks Belgique","article_modified_time":"2022-08-31T10:16:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/","url":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/","name":"Came | Came pour Serrure | Euro-Locks Belgique","isPartOf":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/#primaryimage"},"image":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2021\/12\/C807-500x400-4.png","datePublished":"2021-01-19T11:15:01+00:00","dateModified":"2022-08-31T10:16:54+00:00","description":"Une came est la plaque ou le bras m\u00e9tallique qui, lorsque la serrure est actionn\u00e9e, ouvre ou ferme la serrure. Vous ne savez pas quelle taille de came commander ? Cette page contient des informations sur la mani\u00e8re de sp\u00e9cifier la came dont vous avez beso","breadcrumb":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/#primaryimage","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2021\/12\/C807-500x400-4.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2021\/12\/C807-500x400-4.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/cames\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.euro-locks.com\/be_FR\/"},{"@type":"ListItem","position":2,"name":"Serrure Aide","item":"https:\/\/www.euro-locks.com\/be_FR\/aide\/"},{"@type":"ListItem","position":3,"name":"Informations techniques pour les serrures","item":"https:\/\/www.euro-locks.com\/be_FR\/aide\/informations-techniques\/"},{"@type":"ListItem","position":4,"name":"Cames"}]},{"@type":"WebSite","@id":"https:\/\/www.euro-locks.com\/be_FR\/#website","url":"https:\/\/www.euro-locks.com\/be_FR\/","name":"Euro-Locks Belgique","description":"","publisher":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euro-locks.com\/be_FR\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.euro-locks.com\/be_FR\/#organization","name":"Euro-Locks","url":"https:\/\/www.euro-locks.com\/be_FR\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.euro-locks.com\/be_FR\/#\/schema\/logo\/image\/","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","width":222,"height":58,"caption":"Euro-Locks"},"image":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/euro-locks-group\/","https:\/\/www.youtube.com\/@LoweAndFletcherGroup","https:\/\/www.instagram.com\/lowefletchergroup"]}]}},"_links":{"self":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/pages\/122123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/comments?post=122123"}],"version-history":[{"count":0,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/pages\/122123\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/pages\/122128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/media\/56659"}],"wp:attachment":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/media?parent=122123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}