{"id":129106,"date":"2022-03-18T10:25:22","date_gmt":"2022-08-02T18:00:57","guid":{"rendered":"https:\/\/euro.staging.lowe-and-fletcher.co.uk\/product\/poignee-pivotante-h828\/"},"modified":"2025-09-03T10:14:16","modified_gmt":"2025-09-03T09:14:16","slug":"poignee-pivotante-h828","status":"publish","type":"product","link":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/","title":{"rendered":"Poign\u00e9e pivotante H828"},"content":{"rendered":"<p>L&#8217;anse peut \u00eatre s\u00e9curis\u00e9e \u00e0 l&#8217;aide d&#8217;un cadenas qui offre une couche suppl\u00e9mentaire de s\u00e9curit\u00e9, car une seconde personne ou une cl\u00e9 est n\u00e9cessaire pour acc\u00e9der \u00e0 la poign\u00e9e et la man&#8217;uvrer.<\/p>\n<p>Avec un corps en polyamide 30% fibre de verre pour minimiser le risque d&#8217;\u00e9lectrocution, le mod\u00e8le H828 dispose d&#8217;une poign\u00e9e pivotante escamotable disponible avec un certain nombre d&#8217;options, y compris un cache anti-poussi\u00e8re coulissant, id\u00e9al pour une utilisation sur des armoires.<\/p>\n<p>Contactez-nous d\u00e8s aujourd&#8217;hui pour plus d&#8217;informations sur\u00a0<strong>+32 61 212.261<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poign\u00e9e pivotante H828 avec anse et cylindre europ\u00e9en.<\/p>\n","protected":false},"featured_media":54790,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[2363,42210],"product_tag":[],"class_list":["post-129106","product","type-product","status-publish","has-post-thumbnail","product_cat-poignees","product_cat-poignees-pivotantes","first","instock","purchasable","product-type-grouped"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poign\u00e9e pivotante H828 | Euro-Locks Belgique<\/title>\n<meta name=\"description\" content=\"Poign\u00e9e pivotante H826 disponible en plastique noir d&#039;Euro-Locks Belgique. La poign\u00e9e pivotante en plastique minimise le risque d&#039;\u00e9lectrocution, ce qui la rend id\u00e9ale pour une utilisation sur le march\u00e9 des armoires.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poign\u00e9e pivotante H828 | Euro-Locks Belgique\" \/>\n<meta property=\"og:description\" content=\"Poign\u00e9e pivotante H826 disponible en plastique noir d&#039;Euro-Locks Belgique. La poign\u00e9e pivotante en plastique minimise le risque d&#039;\u00e9lectrocution, ce qui la rend id\u00e9ale pour une utilisation sur le march\u00e9 des armoires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/\" \/>\n<meta property=\"og:site_name\" content=\"Euro-Locks Belgique\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T09:14:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Swing-Handle-with-Shackle-H828.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/poignee-pivotante-h828\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/poignee-pivotante-h828\\\/\",\"name\":\"Poign\u00e9e pivotante H828 | Euro-Locks Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/poignee-pivotante-h828\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/poignee-pivotante-h828\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/Swing-Handle-with-Shackle-H828.jpg\",\"datePublished\":\"2022-08-02T18:00:57+00:00\",\"dateModified\":\"2025-09-03T09:14:16+00:00\",\"description\":\"Poign\u00e9e pivotante H826 disponible en plastique noir d'Euro-Locks Belgique. La poign\u00e9e pivotante en plastique minimise le risque d'\u00e9lectrocution, ce qui la rend id\u00e9ale pour une utilisation sur le march\u00e9 des armoires.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/poignee-pivotante-h828\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/poignee-pivotante-h828\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/poignee-pivotante-h828\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/Swing-Handle-with-Shackle-H828.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/Swing-Handle-with-Shackle-H828.jpg\",\"width\":500,\"height\":500,\"caption\":\"Poign\u00e9e pivotante H828\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/poignee-pivotante-h828\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Poign\u00e9e pivotante H828\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#website\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\",\"name\":\"Euro-Locks Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#organization\",\"name\":\"Euro-Locks\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"width\":222,\"height\":58,\"caption\":\"Euro-Locks\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/euro-locks-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LoweAndFletcherGroup\",\"https:\\\/\\\/www.instagram.com\\\/lowefletchergroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poign\u00e9e pivotante H828 | Euro-Locks Belgique","description":"Poign\u00e9e pivotante H826 disponible en plastique noir d'Euro-Locks Belgique. La poign\u00e9e pivotante en plastique minimise le risque d'\u00e9lectrocution, ce qui la rend id\u00e9ale pour une utilisation sur le march\u00e9 des armoires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/","og_locale":"fr_FR","og_type":"article","og_title":"Poign\u00e9e pivotante H828 | Euro-Locks Belgique","og_description":"Poign\u00e9e pivotante H826 disponible en plastique noir d'Euro-Locks Belgique. La poign\u00e9e pivotante en plastique minimise le risque d'\u00e9lectrocution, ce qui la rend id\u00e9ale pour une utilisation sur le march\u00e9 des armoires.","og_url":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/","og_site_name":"Euro-Locks Belgique","article_modified_time":"2025-09-03T09:14:16+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Swing-Handle-with-Shackle-H828.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/","url":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/","name":"Poign\u00e9e pivotante H828 | Euro-Locks Belgique","isPartOf":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/#primaryimage"},"image":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Swing-Handle-with-Shackle-H828.jpg","datePublished":"2022-08-02T18:00:57+00:00","dateModified":"2025-09-03T09:14:16+00:00","description":"Poign\u00e9e pivotante H826 disponible en plastique noir d'Euro-Locks Belgique. La poign\u00e9e pivotante en plastique minimise le risque d'\u00e9lectrocution, ce qui la rend id\u00e9ale pour une utilisation sur le march\u00e9 des armoires.","breadcrumb":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/#primaryimage","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Swing-Handle-with-Shackle-H828.jpg","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Swing-Handle-with-Shackle-H828.jpg","width":500,"height":500,"caption":"Poign\u00e9e pivotante H828"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/poignee-pivotante-h828\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.euro-locks.com\/be_FR\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.euro-locks.com\/be_FR\/shop\/"},{"@type":"ListItem","position":3,"name":"Poign\u00e9e pivotante H828"}]},{"@type":"WebSite","@id":"https:\/\/www.euro-locks.com\/be_FR\/#website","url":"https:\/\/www.euro-locks.com\/be_FR\/","name":"Euro-Locks Belgique","description":"","publisher":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euro-locks.com\/be_FR\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.euro-locks.com\/be_FR\/#organization","name":"Euro-Locks","url":"https:\/\/www.euro-locks.com\/be_FR\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.euro-locks.com\/be_FR\/#\/schema\/logo\/image\/","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","width":222,"height":58,"caption":"Euro-Locks"},"image":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/euro-locks-group\/","https:\/\/www.youtube.com\/@LoweAndFletcherGroup","https:\/\/www.instagram.com\/lowefletchergroup"]}]}},"_links":{"self":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product\/129106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/media\/54790"}],"wp:attachment":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/media?parent=129106"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_brand?post=129106"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_cat?post=129106"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_tag?post=129106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}