{"id":129507,"date":"2022-03-19T07:51:12","date_gmt":"2022-08-02T19:19:51","guid":{"rendered":"https:\/\/euro.staging.lowe-and-fletcher.co.uk\/product\/serrure-a-code-a151\/"},"modified":"2023-10-17T15:56:56","modified_gmt":"2023-10-17T14:56:56","slug":"serrure-a-code-a151","status":"publish","type":"product","link":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/","title":{"rendered":"Serrure \u00e0 code A151"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Une serrure compacte \u00e0 code \u2013 3 chiffres A151 Euro-Locks. Avec un changement facile de codes et d\u2019activation de code, cette serrure est id\u00e9ale pour de nombreuses applications dont les casiers, le mobilier bois ou m\u00e9tallique et \u00e9vite l\u2019utilisation d\u2019une cl\u00e9.<\/p>\n","protected":false},"featured_media":64516,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[2360],"product_tag":[],"class_list":["post-129507","product","type-product","status-publish","has-post-thumbnail","product_cat-serrures-a-combinaison-mecanique","first","instock","purchasable","product-type-grouped"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serrure \u00e0 code A151 | Serrures \u00e0 combinaison m\u00e9canique<\/title>\n<meta name=\"description\" content=\"Avec un changement facile de codes et d\u2019activation de code, cette serrure est id\u00e9ale pour de nombreuses applications et \u00e9vite l\u2019utilisation d\u2019une cl\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serrure \u00e0 code A151 | Serrures \u00e0 combinaison m\u00e9canique\" \/>\n<meta property=\"og:description\" content=\"Avec un changement facile de codes et d\u2019activation de code, cette serrure est id\u00e9ale pour de nombreuses applications et \u00e9vite l\u2019utilisation d\u2019une cl\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/\" \/>\n<meta property=\"og:site_name\" content=\"Euro-Locks Belgique\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T14:56:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Combination-Lock-A151.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1098\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a151\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a151\\\/\",\"name\":\"Serrure \u00e0 code A151 | Serrures \u00e0 combinaison m\u00e9canique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a151\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a151\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/Combination-Lock-A151.jpg\",\"datePublished\":\"2022-08-02T19:19:51+00:00\",\"dateModified\":\"2023-10-17T14:56:56+00:00\",\"description\":\"Avec un changement facile de codes et d\u2019activation de code, cette serrure est id\u00e9ale pour de nombreuses applications et \u00e9vite l\u2019utilisation d\u2019une cl\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a151\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a151\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a151\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/Combination-Lock-A151.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/Combination-Lock-A151.jpg\",\"width\":1098,\"height\":750,\"caption\":\"Serrure \u00e0 code A151\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a151\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Serrure \u00e0 code A151\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#website\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\",\"name\":\"Euro-Locks Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#organization\",\"name\":\"Euro-Locks\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"width\":222,\"height\":58,\"caption\":\"Euro-Locks\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/euro-locks-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LoweAndFletcherGroup\",\"https:\\\/\\\/www.instagram.com\\\/lowefletchergroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serrure \u00e0 code A151 | Serrures \u00e0 combinaison m\u00e9canique","description":"Avec un changement facile de codes et d\u2019activation de code, cette serrure est id\u00e9ale pour de nombreuses applications et \u00e9vite l\u2019utilisation d\u2019une cl\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/","og_locale":"fr_FR","og_type":"article","og_title":"Serrure \u00e0 code A151 | Serrures \u00e0 combinaison m\u00e9canique","og_description":"Avec un changement facile de codes et d\u2019activation de code, cette serrure est id\u00e9ale pour de nombreuses applications et \u00e9vite l\u2019utilisation d\u2019une cl\u00e9.","og_url":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/","og_site_name":"Euro-Locks Belgique","article_modified_time":"2023-10-17T14:56:56+00:00","og_image":[{"width":1098,"height":750,"url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Combination-Lock-A151.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/","url":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/","name":"Serrure \u00e0 code A151 | Serrures \u00e0 combinaison m\u00e9canique","isPartOf":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/#primaryimage"},"image":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Combination-Lock-A151.jpg","datePublished":"2022-08-02T19:19:51+00:00","dateModified":"2023-10-17T14:56:56+00:00","description":"Avec un changement facile de codes et d\u2019activation de code, cette serrure est id\u00e9ale pour de nombreuses applications et \u00e9vite l\u2019utilisation d\u2019une cl\u00e9.","breadcrumb":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/#primaryimage","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Combination-Lock-A151.jpg","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/Combination-Lock-A151.jpg","width":1098,"height":750,"caption":"Serrure \u00e0 code A151"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a151\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.euro-locks.com\/be_FR\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.euro-locks.com\/be_FR\/shop\/"},{"@type":"ListItem","position":3,"name":"Serrure \u00e0 code A151"}]},{"@type":"WebSite","@id":"https:\/\/www.euro-locks.com\/be_FR\/#website","url":"https:\/\/www.euro-locks.com\/be_FR\/","name":"Euro-Locks Belgique","description":"","publisher":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euro-locks.com\/be_FR\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.euro-locks.com\/be_FR\/#organization","name":"Euro-Locks","url":"https:\/\/www.euro-locks.com\/be_FR\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.euro-locks.com\/be_FR\/#\/schema\/logo\/image\/","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","width":222,"height":58,"caption":"Euro-Locks"},"image":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/euro-locks-group\/","https:\/\/www.youtube.com\/@LoweAndFletcherGroup","https:\/\/www.instagram.com\/lowefletchergroup"]}]}},"_links":{"self":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product\/129507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/media\/64516"}],"wp:attachment":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/media?parent=129507"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_brand?post=129507"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_cat?post=129507"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_tag?post=129507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}