{"id":129508,"date":"2022-03-19T07:51:12","date_gmt":"2022-08-02T19:19:51","guid":{"rendered":"https:\/\/euro.staging.lowe-and-fletcher.co.uk\/product\/serrure-a-code-a152\/"},"modified":"2023-10-17T16:04:14","modified_gmt":"2023-10-17T15:04:14","slug":"serrure-a-code-a152","status":"publish","type":"product","link":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/","title":{"rendered":"Serrure \u00e0 code A152"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Une serrure \u00e0 codes A152 disponible en noir ou gris. Avec 10.000 combinaisons disponibles et un code de brouillage automatique afin de prot\u00e9ger le code utilisateur qui pourrait \u00eatre lu par une tiers personne. Le dernier utilisateur peut programmer et changer son code \u00e0 4 chiffre et avoir une cl\u00e9 passe qui permettra au responsable de voir le code actuel. Disponible en version droite ou gauche, cette serrure est id\u00e9ale pour de nombreuses applications dont le mobilier m\u00e9dical et le mobilier m\u00e9tallique.<\/p>\n","protected":false},"featured_media":57095,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[2360],"product_tag":[],"class_list":["post-129508","product","type-product","status-publish","has-post-thumbnail","product_cat-serrures-a-combinaison-mecanique","first","instock","purchasable","product-type-grouped"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serrure \u00e0 code A152 | Serrures \u00e0 combinaison m\u00e9canique<\/title>\n<meta name=\"description\" content=\"Une serrure \u00e0 combinaison m\u00e9canique \u00e0 4 roues avec 10.000 combinaisons de codes uniques et un brouillage automatique des codes \u00e0 l&#039;entr\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serrure \u00e0 code A152 | Serrures \u00e0 combinaison m\u00e9canique\" \/>\n<meta property=\"og:description\" content=\"Une serrure \u00e0 combinaison m\u00e9canique \u00e0 4 roues avec 10.000 combinaisons de codes uniques et un brouillage automatique des codes \u00e0 l&#039;entr\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/\" \/>\n<meta property=\"og:site_name\" content=\"Euro-Locks Belgique\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T15:04:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/03\/Combination-Lock-A152@2x.png\" \/>\n\t<meta property=\"og:image:width\" content=\"682\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a152\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a152\\\/\",\"name\":\"Serrure \u00e0 code A152 | Serrures \u00e0 combinaison m\u00e9canique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a152\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a152\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/03\\\/Combination-Lock-A152@2x.png\",\"datePublished\":\"2022-08-02T19:19:51+00:00\",\"dateModified\":\"2023-10-17T15:04:14+00:00\",\"description\":\"Une serrure \u00e0 combinaison m\u00e9canique \u00e0 4 roues avec 10.000 combinaisons de codes uniques et un brouillage automatique des codes \u00e0 l'entr\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a152\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a152\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a152\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/03\\\/Combination-Lock-A152@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/03\\\/Combination-Lock-A152@2x.png\",\"width\":682,\"height\":812,\"caption\":\"Serrure \u00e0 code A152\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/produit\\\/serrure-a-code-a152\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Serrure \u00e0 code A152\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#website\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\",\"name\":\"Euro-Locks Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#organization\",\"name\":\"Euro-Locks\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"width\":222,\"height\":58,\"caption\":\"Euro-Locks\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/be_FR\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/euro-locks-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LoweAndFletcherGroup\",\"https:\\\/\\\/www.instagram.com\\\/lowefletchergroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serrure \u00e0 code A152 | Serrures \u00e0 combinaison m\u00e9canique","description":"Une serrure \u00e0 combinaison m\u00e9canique \u00e0 4 roues avec 10.000 combinaisons de codes uniques et un brouillage automatique des codes \u00e0 l'entr\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/","og_locale":"fr_FR","og_type":"article","og_title":"Serrure \u00e0 code A152 | Serrures \u00e0 combinaison m\u00e9canique","og_description":"Une serrure \u00e0 combinaison m\u00e9canique \u00e0 4 roues avec 10.000 combinaisons de codes uniques et un brouillage automatique des codes \u00e0 l'entr\u00e9e.","og_url":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/","og_site_name":"Euro-Locks Belgique","article_modified_time":"2023-10-17T15:04:14+00:00","og_image":[{"width":682,"height":812,"url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/03\/Combination-Lock-A152@2x.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/","url":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/","name":"Serrure \u00e0 code A152 | Serrures \u00e0 combinaison m\u00e9canique","isPartOf":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/#primaryimage"},"image":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/03\/Combination-Lock-A152@2x.png","datePublished":"2022-08-02T19:19:51+00:00","dateModified":"2023-10-17T15:04:14+00:00","description":"Une serrure \u00e0 combinaison m\u00e9canique \u00e0 4 roues avec 10.000 combinaisons de codes uniques et un brouillage automatique des codes \u00e0 l'entr\u00e9e.","breadcrumb":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/#primaryimage","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/03\/Combination-Lock-A152@2x.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/03\/Combination-Lock-A152@2x.png","width":682,"height":812,"caption":"Serrure \u00e0 code A152"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euro-locks.com\/be_FR\/produit\/serrure-a-code-a152\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.euro-locks.com\/be_FR\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.euro-locks.com\/be_FR\/shop\/"},{"@type":"ListItem","position":3,"name":"Serrure \u00e0 code A152"}]},{"@type":"WebSite","@id":"https:\/\/www.euro-locks.com\/be_FR\/#website","url":"https:\/\/www.euro-locks.com\/be_FR\/","name":"Euro-Locks Belgique","description":"","publisher":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euro-locks.com\/be_FR\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.euro-locks.com\/be_FR\/#organization","name":"Euro-Locks","url":"https:\/\/www.euro-locks.com\/be_FR\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.euro-locks.com\/be_FR\/#\/schema\/logo\/image\/","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","width":222,"height":58,"caption":"Euro-Locks"},"image":{"@id":"https:\/\/www.euro-locks.com\/be_FR\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/euro-locks-group\/","https:\/\/www.youtube.com\/@LoweAndFletcherGroup","https:\/\/www.instagram.com\/lowefletchergroup"]}]}},"_links":{"self":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product\/129508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/media\/57095"}],"wp:attachment":[{"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/media?parent=129508"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_brand?post=129508"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_cat?post=129508"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.euro-locks.com\/be_FR\/wp-json\/wp\/v2\/product_tag?post=129508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}