{"id":148998,"date":"2022-03-19T08:00:14","date_gmt":"2022-10-22T11:40:19","guid":{"rendered":"https:\/\/euro.staging.lowe-and-fletcher.co.uk\/product\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/"},"modified":"2023-09-19T12:24:19","modified_gmt":"2023-09-19T11:24:19","slug":"216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810","status":"publish","type":"product","link":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/","title":{"rendered":"21,6mm &#8211; 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>21,6 mm &#8211; 30,0 mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810<\/p>\n","protected":false},"featured_media":41773,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[2403],"product_tag":[],"class_list":["post-148998","product","type-product","status-publish","has-post-thumbnail","product_cat-cerraduras-tubulares","first","instock","purchasable","product-type-grouped"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>21,6mm - 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810<\/title>\n<meta name=\"description\" content=\"Cerradura Llave Tubular con Cambio C\u00f3digo 4810. La combinaci\u00f3n de estos bloqueos se puede cambiar con el uso de una tecla especial (tecla de cambio).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"21,6mm - 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810\" \/>\n<meta property=\"og:description\" content=\"Cerradura Llave Tubular con Cambio C\u00f3digo 4810. La combinaci\u00f3n de estos bloqueos se puede cambiar con el uso de una tecla especial (tecla de cambio).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/\" \/>\n<meta property=\"og:site_name\" content=\"Euro-Locks France\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-19T11:24:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/02\/21.6mm-30mm-Radial-Pin-Tumbler-Code-Change-Lock-4810.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/producto\\\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/producto\\\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\\\/\",\"name\":\"21,6mm - 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/producto\\\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/producto\\\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/21.6mm-30mm-Radial-Pin-Tumbler-Code-Change-Lock-4810.jpg\",\"datePublished\":\"2022-10-22T11:40:19+00:00\",\"dateModified\":\"2023-09-19T11:24:19+00:00\",\"description\":\"Cerradura Llave Tubular con Cambio C\u00f3digo 4810. La combinaci\u00f3n de estos bloqueos se puede cambiar con el uso de una tecla especial (tecla de cambio).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/producto\\\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/producto\\\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/producto\\\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/21.6mm-30mm-Radial-Pin-Tumbler-Code-Change-Lock-4810.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/21.6mm-30mm-Radial-Pin-Tumbler-Code-Change-Lock-4810.jpg\",\"width\":360,\"height\":270,\"caption\":\"Cerradura Llave Tubular con Cambio C\u00f3digo 4810\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/producto\\\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"productos\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"21,6mm &#8211; 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/\",\"name\":\"Euro-Locks France\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/#organization\",\"name\":\"Euro-Locks\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"width\":222,\"height\":58,\"caption\":\"Euro-Locks\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/euro-locks-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LoweAndFletcherGroup\",\"https:\\\/\\\/www.instagram.com\\\/lowefletchergroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"21,6mm - 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810","description":"Cerradura Llave Tubular con Cambio C\u00f3digo 4810. La combinaci\u00f3n de estos bloqueos se puede cambiar con el uso de una tecla especial (tecla de cambio).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/","og_locale":"es_ES","og_type":"article","og_title":"21,6mm - 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810","og_description":"Cerradura Llave Tubular con Cambio C\u00f3digo 4810. La combinaci\u00f3n de estos bloqueos se puede cambiar con el uso de una tecla especial (tecla de cambio).","og_url":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/","og_site_name":"Euro-Locks France","article_modified_time":"2023-09-19T11:24:19+00:00","og_image":[{"width":360,"height":270,"url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/02\/21.6mm-30mm-Radial-Pin-Tumbler-Code-Change-Lock-4810.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/","url":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/","name":"21,6mm - 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810","isPartOf":{"@id":"https:\/\/www.euro-locks.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/#primaryimage"},"image":{"@id":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/02\/21.6mm-30mm-Radial-Pin-Tumbler-Code-Change-Lock-4810.jpg","datePublished":"2022-10-22T11:40:19+00:00","dateModified":"2023-09-19T11:24:19+00:00","description":"Cerradura Llave Tubular con Cambio C\u00f3digo 4810. La combinaci\u00f3n de estos bloqueos se puede cambiar con el uso de una tecla especial (tecla de cambio).","breadcrumb":{"@id":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/#primaryimage","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/02\/21.6mm-30mm-Radial-Pin-Tumbler-Code-Change-Lock-4810.jpg","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/02\/21.6mm-30mm-Radial-Pin-Tumbler-Code-Change-Lock-4810.jpg","width":360,"height":270,"caption":"Cerradura Llave Tubular con Cambio C\u00f3digo 4810"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euro-locks.com\/es\/producto\/216-mm-300-mm-cerradura-llave-tubular-con-cambio-codigo-4810\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.euro-locks.com\/es\/"},{"@type":"ListItem","position":2,"name":"productos","item":"https:\/\/www.euro-locks.com\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"21,6mm &#8211; 30mm Cerradura Llave Tubular con Cambio C\u00f3digo 4810"}]},{"@type":"WebSite","@id":"https:\/\/www.euro-locks.com\/es\/#website","url":"https:\/\/www.euro-locks.com\/es\/","name":"Euro-Locks France","description":"","publisher":{"@id":"https:\/\/www.euro-locks.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euro-locks.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.euro-locks.com\/es\/#organization","name":"Euro-Locks","url":"https:\/\/www.euro-locks.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euro-locks.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","width":222,"height":58,"caption":"Euro-Locks"},"image":{"@id":"https:\/\/www.euro-locks.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/euro-locks-group\/","https:\/\/www.youtube.com\/@LoweAndFletcherGroup","https:\/\/www.instagram.com\/lowefletchergroup"]}]}},"_links":{"self":[{"href":"https:\/\/www.euro-locks.com\/es\/wp-json\/wp\/v2\/product\/148998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euro-locks.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.euro-locks.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/es\/wp-json\/wp\/v2\/media\/41773"}],"wp:attachment":[{"href":"https:\/\/www.euro-locks.com\/es\/wp-json\/wp\/v2\/media?parent=148998"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.euro-locks.com\/es\/wp-json\/wp\/v2\/product_brand?post=148998"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.euro-locks.com\/es\/wp-json\/wp\/v2\/product_cat?post=148998"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.euro-locks.com\/es\/wp-json\/wp\/v2\/product_tag?post=148998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}