{"id":146148,"date":"2022-03-18T10:24:10","date_gmt":"2022-10-16T09:09:07","guid":{"rendered":"https:\/\/euro.staging.lowe-and-fletcher.co.uk\/product\/poignee-de-175-mm-pour-porte-de-garage-1616\/"},"modified":"2023-03-03T15:09:44","modified_gmt":"2023-03-03T15:09:44","slug":"poignee-de-175-mm-pour-porte-de-garage-1616","status":"publish","type":"product","link":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/","title":{"rendered":"Poign\u00e9e de 17,5mm pour porte de garage 1616"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Poign\u00e9e de 17,5 mm pour porte de garage finition argent\u00e9e et noir mat. Cette poign\u00e9e est id\u00e9ale pour une utilisation sur des portes de garage.<\/p>\n","protected":false},"featured_media":37959,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[2280],"product_tag":[],"class_list":["post-146148","product","type-product","status-publish","has-post-thumbnail","product_cat-poignees","first","instock","purchasable","product-type-grouped"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poign\u00e9e de 17,5mm pour porte de garage | Euro-Locks France<\/title>\n<meta name=\"description\" content=\"Poign\u00e9e de 17,5mm pour porte de garage en argent et noir mat d&#039;Euro-Locks. Cette poign\u00e9e est id\u00e9ale pour une utilisation sur des portes de garage.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poign\u00e9e de 17,5mm pour porte de garage | Euro-Locks France\" \/>\n<meta property=\"og:description\" content=\"Poign\u00e9e de 17,5mm pour porte de garage en argent et noir mat d&#039;Euro-Locks. Cette poign\u00e9e est id\u00e9ale pour une utilisation sur des portes de garage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/\" \/>\n<meta property=\"og:site_name\" content=\"Euro-Locks France\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T15:09:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/17.5mm-Garage-Door-Handle-1616.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/produit\\\/poignee-de-175-mm-pour-porte-de-garage-1616\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/produit\\\/poignee-de-175-mm-pour-porte-de-garage-1616\\\/\",\"name\":\"Poign\u00e9e de 17,5mm pour porte de garage | Euro-Locks France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/produit\\\/poignee-de-175-mm-pour-porte-de-garage-1616\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/produit\\\/poignee-de-175-mm-pour-porte-de-garage-1616\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/17.5mm-Garage-Door-Handle-1616.jpg\",\"datePublished\":\"2022-10-16T09:09:07+00:00\",\"dateModified\":\"2023-03-03T15:09:44+00:00\",\"description\":\"Poign\u00e9e de 17,5mm pour porte de garage en argent et noir mat d'Euro-Locks. Cette poign\u00e9e est id\u00e9ale pour une utilisation sur des portes de garage.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/produit\\\/poignee-de-175-mm-pour-porte-de-garage-1616\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/produit\\\/poignee-de-175-mm-pour-porte-de-garage-1616\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/produit\\\/poignee-de-175-mm-pour-porte-de-garage-1616\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/17.5mm-Garage-Door-Handle-1616.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/17.5mm-Garage-Door-Handle-1616.jpg\",\"width\":1600,\"height\":1200,\"caption\":\"Poign\u00e9e de 17.5mm pour porte de garage 1616\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/produit\\\/poignee-de-175-mm-pour-porte-de-garage-1616\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Poign\u00e9e de 17,5mm pour porte de garage 1616\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/\",\"name\":\"Euro-Locks France\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/#organization\",\"name\":\"Euro-Locks\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"width\":222,\"height\":58,\"caption\":\"Euro-Locks\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/euro-locks-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LoweAndFletcherGroup\",\"https:\\\/\\\/www.instagram.com\\\/lowefletchergroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poign\u00e9e de 17,5mm pour porte de garage | Euro-Locks France","description":"Poign\u00e9e de 17,5mm pour porte de garage en argent et noir mat d'Euro-Locks. Cette poign\u00e9e est id\u00e9ale pour une utilisation sur des portes de garage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/","og_locale":"fr_FR","og_type":"article","og_title":"Poign\u00e9e de 17,5mm pour porte de garage | Euro-Locks France","og_description":"Poign\u00e9e de 17,5mm pour porte de garage en argent et noir mat d'Euro-Locks. Cette poign\u00e9e est id\u00e9ale pour une utilisation sur des portes de garage.","og_url":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/","og_site_name":"Euro-Locks France","article_modified_time":"2023-03-03T15:09:44+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/17.5mm-Garage-Door-Handle-1616.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/","url":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/","name":"Poign\u00e9e de 17,5mm pour porte de garage | Euro-Locks France","isPartOf":{"@id":"https:\/\/www.euro-locks.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/#primaryimage"},"image":{"@id":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/17.5mm-Garage-Door-Handle-1616.jpg","datePublished":"2022-10-16T09:09:07+00:00","dateModified":"2023-03-03T15:09:44+00:00","description":"Poign\u00e9e de 17,5mm pour porte de garage en argent et noir mat d'Euro-Locks. Cette poign\u00e9e est id\u00e9ale pour une utilisation sur des portes de garage.","breadcrumb":{"@id":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/#primaryimage","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/17.5mm-Garage-Door-Handle-1616.jpg","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/01\/17.5mm-Garage-Door-Handle-1616.jpg","width":1600,"height":1200,"caption":"Poign\u00e9e de 17.5mm pour porte de garage 1616"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euro-locks.com\/fr\/produit\/poignee-de-175-mm-pour-porte-de-garage-1616\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.euro-locks.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.euro-locks.com\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Poign\u00e9e de 17,5mm pour porte de garage 1616"}]},{"@type":"WebSite","@id":"https:\/\/www.euro-locks.com\/fr\/#website","url":"https:\/\/www.euro-locks.com\/fr\/","name":"Euro-Locks France","description":"","publisher":{"@id":"https:\/\/www.euro-locks.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euro-locks.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.euro-locks.com\/fr\/#organization","name":"Euro-Locks","url":"https:\/\/www.euro-locks.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.euro-locks.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","width":222,"height":58,"caption":"Euro-Locks"},"image":{"@id":"https:\/\/www.euro-locks.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/euro-locks-group\/","https:\/\/www.youtube.com\/@LoweAndFletcherGroup","https:\/\/www.instagram.com\/lowefletchergroup"]}]}},"_links":{"self":[{"href":"https:\/\/www.euro-locks.com\/fr\/wp-json\/wp\/v2\/product\/146148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euro-locks.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.euro-locks.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/fr\/wp-json\/wp\/v2\/media\/37959"}],"wp:attachment":[{"href":"https:\/\/www.euro-locks.com\/fr\/wp-json\/wp\/v2\/media?parent=146148"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.euro-locks.com\/fr\/wp-json\/wp\/v2\/product_brand?post=146148"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.euro-locks.com\/fr\/wp-json\/wp\/v2\/product_cat?post=146148"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.euro-locks.com\/fr\/wp-json\/wp\/v2\/product_tag?post=146148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}