{"id":386095,"date":"2025-10-07T13:40:25","date_gmt":"2025-10-07T12:40:25","guid":{"rendered":"https:\/\/www.euro-locks.com\/?p=386095"},"modified":"2025-10-07T13:40:25","modified_gmt":"2025-10-07T12:40:25","slug":"echo-lock-finalista-degli-fx-design-awards-2025","status":"publish","type":"post","link":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/","title":{"rendered":"ECHO Lock &#8211; Finalista degli FX Design Awards 2025!"},"content":{"rendered":"<p>Lowe &amp; Fletcher ed Euro-Locks sono lieti di annunciare che la rivoluzionaria ECHO Lock \u00e8 finalista come Prodotto dell&#8217;Anno agli FX Design Awards 2025!<\/p>\n<p>I prestigiosi FX Awards invitano talenti del design britannico e internazionale provenienti da tutto il mondo a presentare il meglio dei prodotti e dei progetti di interni. I premi vengono poi giudicati da una giuria invitata di illustri esperti dell&#8217;industria del design, tra cui designer, architetti, ingegneri e i loro clienti.<\/p>\n<p>I vincitori saranno rivelati durante una cena e cerimonia di premiazione il 26 novembre 2025, incrociando le dita!<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-384847\" src=\"https:\/\/www.lowe-and-fletcher.co.uk\/wp-content\/uploads\/2025\/09\/ECHO-Lock_Montage-1-122024-600x376.jpg\" alt=\"\" width=\"600\" height=\"376\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lowe &amp; Fletcher ed Euro-Locks sono lieti di annunciare che la rivoluzionaria ECHO Lock \u00e8 finalista come Prodotto dell&#8217;Anno agli FX Design Awards 2025! I prestigiosi FX Awards invitano talenti del design britannico e internazionale provenienti da tutto il mondo a presentare il meglio dei prodotti e dei progetti di interni. I premi vengono poi [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":386013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[42205],"tags":[2159],"class_list":["post-386095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-blog","tag-aggiornamenti-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ECHO Lock - Finalista degli FX Design Awards 2025!<\/title>\n<meta name=\"description\" content=\"Siamo lieti di annunciare che la nostra serratura ECHO \u00e8 stata selezionata come prodotto dell&#039;anno agli FX Design Awards 2025!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ECHO Lock - Finalista degli FX Design Awards 2025!\" \/>\n<meta property=\"og:description\" content=\"Siamo lieti di annunciare che la nostra serratura ECHO \u00e8 stata selezionata come prodotto dell&#039;anno agli FX Design Awards 2025!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Euro-Locks SA NV\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T12:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2025\/09\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rachael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"rachael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/\"},\"author\":{\"name\":\"rachael\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#\\\/schema\\\/person\\\/645c8ede49de8f954df4eb6cd371f04f\"},\"headline\":\"ECHO Lock &#8211; Finalista degli FX Design Awards 2025!\",\"datePublished\":\"2025-10-07T12:40:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/\"},\"wordCount\":99,\"publisher\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/09\\\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg\",\"keywords\":[\"Aggiornamenti\"],\"articleSection\":[\"Notizie e blog\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/\",\"name\":\"ECHO Lock - Finalista degli FX Design Awards 2025!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/09\\\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg\",\"datePublished\":\"2025-10-07T12:40:25+00:00\",\"description\":\"Siamo lieti di annunciare che la nostra serratura ECHO \u00e8 stata selezionata come prodotto dell'anno agli FX Design Awards 2025!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/09\\\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/09\\\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Siamo lieti di annunciare che la nostra serratura ECHO \u00e8 stata selezionata come prodotto dell'anno agli FX Design Awards 2025!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/notizie-e-blog\\\/echo-lock-finalista-degli-fx-design-awards-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ECHO Lock &#8211; Finalista degli FX Design Awards 2025!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/\",\"name\":\"Euro-Locks SA NV\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#organization\",\"name\":\"Euro-Locks\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"contentUrl\":\"https:\\\/\\\/www.euro-locks.com\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/EL-Logo-Primary-2-e1651247803393.png\",\"width\":222,\"height\":58,\"caption\":\"Euro-Locks\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/euro-locks-group\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@LoweAndFletcherGroup\",\"https:\\\/\\\/www.instagram.com\\\/lowefletchergroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/#\\\/schema\\\/person\\\/645c8ede49de8f954df4eb6cd371f04f\",\"name\":\"rachael\",\"url\":\"https:\\\/\\\/www.euro-locks.com\\\/it\\\/author\\\/rachael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECHO Lock - Finalista degli FX Design Awards 2025!","description":"Siamo lieti di annunciare che la nostra serratura ECHO \u00e8 stata selezionata come prodotto dell'anno agli FX Design Awards 2025!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/","og_locale":"it_IT","og_type":"article","og_title":"ECHO Lock - Finalista degli FX Design Awards 2025!","og_description":"Siamo lieti di annunciare che la nostra serratura ECHO \u00e8 stata selezionata come prodotto dell'anno agli FX Design Awards 2025!","og_url":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/","og_site_name":"Euro-Locks SA NV","article_published_time":"2025-10-07T12:40:25+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2025\/09\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg","type":"image\/jpeg"}],"author":"rachael","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"rachael","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/#article","isPartOf":{"@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/"},"author":{"name":"rachael","@id":"https:\/\/www.euro-locks.com\/it\/#\/schema\/person\/645c8ede49de8f954df4eb6cd371f04f"},"headline":"ECHO Lock &#8211; Finalista degli FX Design Awards 2025!","datePublished":"2025-10-07T12:40:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/"},"wordCount":99,"publisher":{"@id":"https:\/\/www.euro-locks.com\/it\/#organization"},"image":{"@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2025\/09\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg","keywords":["Aggiornamenti"],"articleSection":["Notizie e blog"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/","url":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/","name":"ECHO Lock - Finalista degli FX Design Awards 2025!","isPartOf":{"@id":"https:\/\/www.euro-locks.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2025\/09\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg","datePublished":"2025-10-07T12:40:25+00:00","description":"Siamo lieti di annunciare che la nostra serratura ECHO \u00e8 stata selezionata come prodotto dell'anno agli FX Design Awards 2025!","breadcrumb":{"@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/#primaryimage","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2025\/09\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2025\/09\/FX-Awards-2025-Finalist-logo-Linkedin-1200x627-1.jpg","width":1200,"height":627,"caption":"Siamo lieti di annunciare che la nostra serratura ECHO \u00e8 stata selezionata come prodotto dell'anno agli FX Design Awards 2025!"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euro-locks.com\/it\/notizie-e-blog\/echo-lock-finalista-degli-fx-design-awards-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.euro-locks.com\/it\/"},{"@type":"ListItem","position":2,"name":"ECHO Lock &#8211; Finalista degli FX Design Awards 2025!"}]},{"@type":"WebSite","@id":"https:\/\/www.euro-locks.com\/it\/#website","url":"https:\/\/www.euro-locks.com\/it\/","name":"Euro-Locks SA NV","description":"","publisher":{"@id":"https:\/\/www.euro-locks.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euro-locks.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.euro-locks.com\/it\/#organization","name":"Euro-Locks","url":"https:\/\/www.euro-locks.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.euro-locks.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","contentUrl":"https:\/\/www.euro-locks.com\/wp-content\/uploads\/sites\/4\/2022\/04\/EL-Logo-Primary-2-e1651247803393.png","width":222,"height":58,"caption":"Euro-Locks"},"image":{"@id":"https:\/\/www.euro-locks.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/euro-locks-group\/","https:\/\/www.youtube.com\/@LoweAndFletcherGroup","https:\/\/www.instagram.com\/lowefletchergroup"]},{"@type":"Person","@id":"https:\/\/www.euro-locks.com\/it\/#\/schema\/person\/645c8ede49de8f954df4eb6cd371f04f","name":"rachael","url":"https:\/\/www.euro-locks.com\/it\/author\/rachael\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/posts\/386095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/comments?post=386095"}],"version-history":[{"count":1,"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/posts\/386095\/revisions"}],"predecessor-version":[{"id":386096,"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/posts\/386095\/revisions\/386096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/media\/386013"}],"wp:attachment":[{"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/media?parent=386095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/categories?post=386095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euro-locks.com\/it\/wp-json\/wp\/v2\/tags?post=386095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}